{"id":432,"date":"2021-06-10T19:07:15","date_gmt":"2021-06-10T17:07:15","guid":{"rendered":"https:\/\/blogs.ugr.es\/inventate\/?p=432"},"modified":"2021-06-10T19:07:43","modified_gmt":"2021-06-10T17:07:43","slug":"curso-online-proyecto-de-videocreacion","status":"publish","type":"post","link":"https:\/\/blogs.ugr.es\/inventate\/curso-online-proyecto-de-videocreacion\/","title":{"rendered":"CURSO ONLINE:  PROYECTO DE VIDEOCREACI\u00d3N"},"content":{"rendered":"<p>\u00abLo que nunca te contaron de los cuentos cl\u00e1sicos \u00bb<\/p>\n<p>PROP\u00d3SITO: Desarrollar una experiencia de filmaci\u00f3n y edici\u00f3n de creaci\u00f3n colectiva.<\/p>\n<p>Un laboratorio que incluye: preparaci\u00f3n, investigaci\u00f3n, guionizaci\u00f3n, improvisaci\u00f3n, jugacci\u00f3n, buf\u00f3n, clown, filmaci\u00f3n y diversi\u00f3n.<\/p>\n<p>CONJUNTO:<\/p>\n<ol>\n<li>El tr\u00e1iler.<\/li>\n<li>El falso documental llamado \u00abAs\u00edn se hizo\u00bb.<\/li>\n<li>De 1 a 3 cap\u00edtulos, con un m\u00e1ximo de 5 minutos por cap\u00edtulo en co-creaci\u00f3n colectiva.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Facilita: Salva Atienza Valiente \/SALVA TRASTO<\/p>\n<p>Coordinaci\u00f3n: Proexdra. Alfredo Mantovani<\/p>\n<p>HORARIO:<\/p>\n<p>Tres lunes cada 15 d\u00edas.\u00a0 D\u00edas 14 y 28 de junio y 12 de julio de 2021.<\/p>\n<p>De 19: 00 hs a 21: 00 hs.<\/p>\n<p>INVERSI\u00d3N: 45, 00 euros.<\/p>\n<p>Plazas limitadas: m\u00e1ximo 14 personas. M\u00ednimo: 10 personas.Arriban estas propuestas para arrancar el viaje de la videocreaci\u00f3n&#8230;<\/p>\n<p>Propuestas previas al primer d\u00eda de encuentro ONLINE:<\/p>\n<p>Arriban estas propuestas para arrancar el viaje de la videocreaci\u00f3n&#8230;<\/p>\n<ul>\n<li>Empaparse a releer cuentos cl\u00e1sicos (Al estilo de los cuentos Andersen&#8230;)<\/li>\n<li>Bucear y buscar en la memoria aquel cuento cl\u00e1sico favorito de tu infancia, releerlo. (A ser posible en sus versiones m\u00e1s arcaicas).<\/li>\n<li>Elegir un personaje que aparezca en un Cuento Cl\u00e1sico. Por ejemplo: la bestia del cuento La bella y la bestia, una de las hermanastras de Cenicienta, uno de los patos hermanastros del patito feo&#8230; No tienen que ser los personajes principales, aunque tambi\u00e9n es posible que sean los protagonistas. Hacer un texto, escribir en primera persona, con la confesi\u00f3n delirante de dicho personaje, sus vicisitudes, malestares, gozos, ventajas e inconvenientes&#8230;<\/li>\n<li>Traer alg\u00fan elemento de vestuario Cl\u00e1sico, a saber&#8230; Sombrero, capa, bast\u00f3n, pa\u00f1uelo, pluma, espada&#8230;<\/li>\n<\/ul>\n<p>Y respirar la diversi\u00f3n \u201cCl\u00e1sica\u201d de nuestro proyecto de video-creaci\u00f3n ya en marcha.<\/p>\n<p>Alfredo Mantovani, coordinador\u00a0 M\u00f3vil 692674854<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLo que nunca te contaron de los cuentos cl\u00e1sicos \u00bb PROP\u00d3SITO: Desarrollar una experiencia de filmaci\u00f3n y edici\u00f3n de creaci\u00f3n colectiva. Un laboratorio que incluye: preparaci\u00f3n, investigaci\u00f3n, guionizaci\u00f3n, improvisaci\u00f3n, jugacci\u00f3n, buf\u00f3n, clown, filmaci\u00f3n y diversi\u00f3n. CONJUNTO: El tr\u00e1iler. El falso documental llamado \u00abAs\u00edn se hizo\u00bb. De 1 a 3 cap\u00edtulos, con un m\u00e1ximo de 5 [&hellip;]<\/p>\n","protected":false},"author":572,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-432","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-difusion","7":"entry"},"_links":{"self":[{"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/posts\/432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/users\/572"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/comments?post=432"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/posts\/432\/revisions"}],"predecessor-version":[{"id":434,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/posts\/432\/revisions\/434"}],"wp:attachment":[{"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/media?parent=432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/categories?post=432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ugr.es\/inventate\/wp-json\/wp\/v2\/tags?post=432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}